{"id":3832,"date":"2025-11-10T14:16:08","date_gmt":"2025-11-10T13:16:08","guid":{"rendered":"https:\/\/www.molinipivetti.it\/farine-a-ridotto-impatto-ambientale-molini-pivetti-e-yara-italia-avviano-il-piano-per-la-diminuzione-dellimpronta-carbonica-della-filiera-campi-protetti-pivetti\/"},"modified":"2025-11-10T15:10:31","modified_gmt":"2025-11-10T14:10:31","slug":"mehl-mit-reduzierter-umweltbelastung-molini-pivetti-und-yara-italia-starten-einen-plan-zur-verringerung-des-co2-fussabdrucks-der-lieferkette-campi-protetti-pivetti","status":"publish","type":"post","link":"https:\/\/www.molinipivetti.it\/de\/mehl-mit-reduzierter-umweltbelastung-molini-pivetti-und-yara-italia-starten-einen-plan-zur-verringerung-des-co2-fussabdrucks-der-lieferkette-campi-protetti-pivetti\/","title":{"rendered":"Mehl mit reduzierter Umweltbelastung: Molini Pivetti und Yara Italia starten einen Plan zur Verringerung des CO2-Fu\u00dfabdrucks der Lieferkette Campi Protetti Pivetti"},"content":{"rendered":"[vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;custom&#8220; custom_text_color=&#8220;#202020&#8243; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;10\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;80px&#8220; custom_height_tablet=&#8220;80px&#8220; custom_height_phone=&#8220;60px&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;full_width_background&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;custom&#8220; custom_text_color=&#8220;#202020&#8243; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;10\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]\n<h2 class=\"custom-font-size-h3\">Die Ank\u00fcndigung stand im Mittelpunkt des Treffens mit den Landwirten der Lieferkette Campi Protetti Pivetti und sieht eine weitere Senkung der CO\u2082-Emissionen in der Anbauphase von Weichweizen durch den Einsatz von Yara Climate Choice\u2122-D\u00fcngemitteln vor.<\/h2>\n[\/vc_column_text][divider line_type=&#8220;No Line&#8220; custom_height=&#8220;40px&#8220;][vc_row_inner column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; text_align=&#8220;left&#8220; row_position=&#8220;default&#8220; row_position_tablet=&#8220;inherit&#8220; row_position_phone=&#8220;inherit&#8220; overflow=&#8220;visible&#8220; pointer_events=&#8220;all&#8220;][vc_column_inner column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; overflow=&#8220;visible&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text css=&#8220;&#8220; text_direction=&#8220;default&#8220;]<em>Renazzo (FE), 10. November 2025 &#8211;<\/em>Molini Pivetti, Italiens f\u00fchrender Getreidem\u00fchlenbetrieb, und <a href=\"https:\/\/www.yara.it\/\" target=\"_blank\" rel=\"noopener nofollow\">Yara Italia<\/a>, Marktf\u00fchrer im Bereich Pflanzenern\u00e4hrung und nachhaltige Landwirtschaft, starten ein gemeinsames Projekt zur Reduzierung des CO2-Fu\u00dfabdrucks beim Anbau von Weichweizen f\u00fcr eine nachhaltigere Landwirtschaft.<\/p>\n<p>Die Ank\u00fcndigung stand im Mittelpunkt des Treffens am vergangenen Freitag mit den Landwirten der Lieferkette Campi Protetti Pivetti, einem vorbildlichen Modell f\u00fcr verantwortungsbewusste Produktion, das das Aush\u00e4ngeschild von Molini Pivetti und der Region Emilia ist, die seit jeher f\u00fcr den Anbau von Weichweizen bekannt ist. Aus diesen Feldern entstehen hochwertige Mehle, die zu 100 % aus der Emilia stammen, wie Gran Riserva und Da Agricoltura Sostenibile.<\/p>\n<p>Die Partnerschaft zwischen Molini Pivetti und Yara Italia wurde 2024 unterzeichnet. Das Ziel: die Nachhaltigkeit des Weichweizenanbaus der Lieferkette Campi Protetti Pivetti durch fortschrittliche D\u00fcngungspraktiken und innovative digitale Technologien zu verbessern und gleichzeitig die Beziehung zu den Landwirten zu st\u00e4rken.<\/p>\n<p>Dank der Zusammenarbeit des technischen Teams von Molini Pivetti mit dem internationalen Team von Yara, das sich der Forschung und Entwicklung im agronomischen Bereich widmet, wurden in der Vorphase die agronomischen Praktiken mit besonderem Augenmerk auf den Einsatz von D\u00fcngemitteln analysiert, sowohl durch Feldversuche als auch durch die Analyse historischer Daten der Lieferkette.<\/p>\n<p>Das Ergebnis dieser ersten Vergleiche f\u00fchrte zur Festlegung eines spezifischen und gezielten Ern\u00e4hrungsplans, der den Einsatz von Yara Climate Choice\u2122-D\u00fcngemitteln als strategisches Instrument zur weiteren Verringerung des CO2-Fu\u00dfabdrucks des Weichweizenanbaus vorsieht.<\/p>\n<p>Nun beginnt die \u201ePilot\u201d-Testphase, in der der auf die Bed\u00fcrfnisse der landwirtschaftlichen Lieferkette von Campi Protetti Pivetti abgestimmte Ern\u00e4hrungsplan umgesetzt wird.<\/p>\n<p>Der Einsatz von Yara Climate Choice\u2122-D\u00fcngemitteln im Pilotprojekt wird es den Landwirten erm\u00f6glichen, ihre Ertr\u00e4ge zu optimieren und gleichzeitig die Umweltbelastung zu reduzieren, und Molini Pivetti wird ein Mehl mit reduziertem CO2-Fu\u00dfabdruck erhalten, ein Mehrwert, der sich nahtlos in den Nachhaltigkeitsprozess einf\u00fcgt, den das Unternehmen seit mehreren Jahren verfolgt.<\/p>\n<p>Der CO2-Fu\u00dfabdruck des Weichweizenanbaus entspricht der Gesamtmenge der Treibhausgase, die w\u00e4hrend aller Phasen des landwirtschaftlichen Prozesses ausgesto\u00dfen werden, und liegt bei etwa 60 %: von der Herstellung und Verwendung von D\u00fcngemitteln \u00fcber den Kraftstoffverbrauch f\u00fcr die Bodenbearbeitung bis hin zur Bew\u00e4sserung, zum Transport und zur Entsorgung von Ernter\u00fcckst\u00e4nden.<\/p>\n<p><em>\u201eAus der seit 2018 f\u00fcr jedes Jahr durchgef\u00fchrten \u00d6kobilanz (Life Cycle Assessment, LCA) geht eindeutig hervor, dass die landwirtschaftliche Phase einen entscheidenden Einfluss auf den CO2-Fu\u00dfabdruck der Weichweizenmehlproduktion von Molini Pivetti hat. Dies hat das Unternehmen dazu veranlasst, einen verantwortungsvolleren Anbau zu f\u00f6rdern und die Zusammenarbeit mit den Landwirten zu verst\u00e4rken. Daraus entstand das Projekt \u201eCampi Protetti Pivetti\u201c (Gesch\u00fctzte Felder von Pivetti), ein CSQA-zertifiziertes Label, das eine in jeder Phase r\u00fcckverfolgbare und kontrollierte Lieferkette kennzeichnet und die italienische Herkunft des Getreides sowie das Engagement f\u00fcr eine Landwirtschaft garantiert, die zuk\u00fcnftige Generationen sch\u00fctzt und gleichzeitig die Umwelt schont. Aus dem gleichen Engagement entstehen auch strategische Kooperationen, wie die mit Yara Italia, die darauf abzielen, immer nachhaltigere landwirtschaftliche Praktiken entlang der gesamten Lieferkette umzusetzen\u201d<\/em>, erkl\u00e4rte Alessandro Zucchi, Agronom und Leiter der Lieferkettenprojekte bei Molini Pivetti.<\/p>\n<p><em>\u201eDie Zusammenarbeit mit Molini Pivetti, einem seit \u00fcber 150 Jahren in Italien verwurzelten Unternehmen, erf\u00fcllt Yara mit Stolz und Begeisterung\u201c,<\/em> so Giulia Castellucci, Supply Chain Relations Managerin von Yara Italien. <em>\u201eDiese Partnerschaft zeigt, wie sich Yaras Produktinnovationen nahtlos in die Tradition italienischer Exzellenz einf\u00fcgen und historisches Know-how mit modernsten Technologien im Agrarsektor verbinden. Yara Climate Choice\u2122-D\u00fcnger sind ein einfach anzuwendendes Instrument, um die Umweltauswirkungen der Agrar- und Lebensmittelversorgungsketten zu reduzieren.\u201c<\/em><\/p>\n<p>Die D\u00fcngemittel Yara Climate Choice\u2122 sind dieselben zuverl\u00e4ssigen und hochwertigen Produkte von Yara f\u00fcr die Pflanzenern\u00e4hrung, werden jedoch mit neuen Technologien hergestellt, die den CO2-Fu\u00dfabdruck der D\u00fcngemittelproduktion im Werk weiter reduzieren, beispielsweise durch die Verwendung von Ammoniak aus erneuerbaren Quellen oder durch CO2-Abscheidung und -Speicherung. Yara garantiert die G\u00fcltigkeit der Berechnungen zur Messung des CO2-Fu\u00dfabdrucks der Produkte durch die Zertifizierung einer unabh\u00e4ngigen dritten Stelle.[\/vc_column_text][divider line_type=&#8220;No Line&#8220;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/12&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220; gradient_type=&#8220;default&#8220; shape_type=&#8220;&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;]<div class=\"templatera_shortcode\">\n\t\t<div id=\"fws_6a57e391e6bf7\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"margin-top: 12.5px; height: 1px; margin-bottom: 12.5px;\" data-width=\"100%\" data-animate=\"yes\" data-animation-delay=\"\" data-color=\"extra-color-1\" class=\"divider-border\"><\/div><\/div><div class=\"divider-wrap height_tablet_70px height_phone_50px \" data-alignment=\"default\"><div style=\"height: 90px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a57e391e7f43\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-7 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<h2 style=\"color: #fa554f;\">Se sei un professionista,\u2028scegli le farine Molini Pivetti<\/h2>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-5 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a57e391e939c\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-7 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 10px;\" class=\"divider\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element \" >\n\t<p>Vuoi sapere qual \u00e8 la farina pi\u00f9 giusta per te? Hai bisogno di maggiori informazioni sulle nostre farine per professionisti? Desideri sapere dove poterle acquistare?<br \/>\nCompila il nostro form contatti e chiedi ulteriori informazioni, sar\u00e0 un piacere aiutarti.<\/p>\n<\/div>\n\n\n\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 50px;\" class=\"divider\"><\/div><\/div><a class=\"nectar-button jumbo regular accent-color  regular-button\"  role=\"button\" style=\"\"  href=\"\/contatti\/\" data-color-override=\"false\" data-hover-color-override=\"false\" data-hover-text-color-override=\"#fff\"><span>Contattaci<\/span><\/a><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-5 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div><\/div>[\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"Die Ank\u00fcndigung stand im Mittelpunkt des Treffens mit den Landwirten der Lieferkette Campi Protetti Pivetti und sieht eine weitere Senkung der CO\u2082-Emissionen in der Anbauphase von Weichweizen durch den Einsatz...","protected":false},"author":2,"featured_media":3821,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[133],"tags":[],"class_list":["post-3832","post","type-post","status-publish","format-standard","has-post-thumbnail","category-pressemitteilungen"],"_links":{"self":[{"href":"https:\/\/www.molinipivetti.it\/de\/wp-json\/wp\/v2\/posts\/3832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.molinipivetti.it\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.molinipivetti.it\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.molinipivetti.it\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.molinipivetti.it\/de\/wp-json\/wp\/v2\/comments?post=3832"}],"version-history":[{"count":4,"href":"https:\/\/www.molinipivetti.it\/de\/wp-json\/wp\/v2\/posts\/3832\/revisions"}],"predecessor-version":[{"id":3836,"href":"https:\/\/www.molinipivetti.it\/de\/wp-json\/wp\/v2\/posts\/3832\/revisions\/3836"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.molinipivetti.it\/de\/wp-json\/wp\/v2\/media\/3821"}],"wp:attachment":[{"href":"https:\/\/www.molinipivetti.it\/de\/wp-json\/wp\/v2\/media?parent=3832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.molinipivetti.it\/de\/wp-json\/wp\/v2\/categories?post=3832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.molinipivetti.it\/de\/wp-json\/wp\/v2\/tags?post=3832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}